{"id":2415,"date":"2023-09-05T22:09:36","date_gmt":"2023-09-06T01:09:36","guid":{"rendered":"https:\/\/mktlobo.com\/loja\/?post_type=product&amp;p=2415"},"modified":"2023-09-05T22:09:36","modified_gmt":"2023-09-06T01:09:36","slug":"pacote-para-arquitetos-e-engenheiros","status":"publish","type":"product","link":"https:\/\/mktlobo.com\/loja\/produto\/pacote-para-arquitetos-e-engenheiros\/","title":{"rendered":"Pacote para Arquitetos e Engenheiros"},"content":{"rendered":"<ul>\n<li>\u00a0Logotipo principal (para uso em redes sociais e impressos)<\/li>\n<li>Logotipo Alternativo (outros formatos do seu logotipo)<\/li>\n<li>Paleta de cores (c\u00f3digos das cores)<\/li>\n<li>Marcas d\u2019agua (seu logo sem fundo para aplica\u00e7\u00e3o em fotos e posts)<\/li>\n<li>Pattern (estampa da marca)<\/li>\n<li>1 Arte para cart\u00e3o de visita<\/li>\n<li>1 Arte p ara papel timbrado<\/li>\n<li>1 Arte de pasta A4 ou A3<\/li>\n<li>1 Arte de envelope<\/li>\n<li>02 Templates para Instagram<\/li>\n<li>1 Arte de placa de obra. \u2013 Manual da Marca com aplica\u00e7\u00f5es do logotipo em imagens realistas<\/li>\n<li>Brinde -pack\u00a0 templates edit\u00e1veis canva<\/li>\n<\/ul>\n<p>Em at\u00e9 48h, enviaremos um e-mail com o question\u00e1rio. Ap\u00f3s o recebimento do mesmo, enviaremos, no prazo de 25-27 dias, A apresenta\u00e7\u00e3o da marca para aprova\u00e7\u00e3o. O cliente pode fazer at\u00e9 5 (cinco) altera\u00e7\u00f5es sem custo. Ap\u00f3s este n\u00famero o cliente deve pagar R$20 por nova altera\u00e7\u00e3o. O prazo para cada altera\u00e7\u00e3o vai depender do grau de complexidade, mas geralmente estabelecemos 2 a 3 dias \u00fateis.<\/p>\n<p>Ap\u00f3s APROVADO n\u00e3o faremos mais altera\u00e7\u00f5es<\/p>\n<p>Os arquivos ser\u00e3o enviados nos formatos de imagem PNG. e Vetores EPS. PDF. e Ai.<\/p>\n<p>Cancelamentos e Devolu\u00e7\u00f5es:<br \/>\nSem pr\u00e9vias enviadas ou em at\u00e9 7 dias corridos: 100% do valor;<\/p>\n<p>Pr\u00e9vias enviadas e n\u00e3o alteradas: 50% do valor;<\/p>\n<p>Projeto enviado e alterado ainda nas pr\u00e9vias: 35% do valor;<\/p>\n<p>Projeto enviado, alterado nas pr\u00e9vias e na apresenta\u00e7\u00e3o final: 20% do valor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Logotipo principal (para uso em redes sociais e impressos) Logotipo Alternativo (outros formatos do seu logotipo) Paleta de cores (c\u00f3digos [&hellip;]<\/p>\n","protected":false},"featured_media":2416,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[19],"product_tag":[],"class_list":["post-2415","product","type-product","status-publish","has-post-thumbnail","product_cat-servicos","first","instock","virtual","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/mktlobo.com\/loja\/wp-json\/wp\/v2\/product\/2415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mktlobo.com\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mktlobo.com\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mktlobo.com\/loja\/wp-json\/wp\/v2\/comments?post=2415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mktlobo.com\/loja\/wp-json\/wp\/v2\/media\/2416"}],"wp:attachment":[{"href":"https:\/\/mktlobo.com\/loja\/wp-json\/wp\/v2\/media?parent=2415"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mktlobo.com\/loja\/wp-json\/wp\/v2\/product_brand?post=2415"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mktlobo.com\/loja\/wp-json\/wp\/v2\/product_cat?post=2415"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mktlobo.com\/loja\/wp-json\/wp\/v2\/product_tag?post=2415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}